{"id":19737,"date":"2022-11-09T14:44:02","date_gmt":"2022-11-09T13:44:02","guid":{"rendered":"https:\/\/dynamika.com\/about-us-dynamika\/"},"modified":"2025-06-30T15:42:31","modified_gmt":"2025-06-30T13:42:31","slug":"about-us-dynamika","status":"publish","type":"page","link":"https:\/\/dynamika.com\/en\/about-us-dynamika\/","title":{"rendered":"About Us &#8211; Dynamika"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"19737\" class=\"elementor elementor-19737 elementor-4512\" data-elementor-post-type=\"page\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-a6b09b3 e-flex e-con-boxed e-con e-parent\" data-id=\"a6b09b3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-9a69f0d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"9a69f0d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dd762e8\" data-id=\"dd762e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-627df27 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"627df27\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-59fc31f\" data-id=\"59fc31f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54e5b67 elementor-widget elementor-widget-marity_core_section_title\" data-id=\"54e5b67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"marity_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-show_supertitle--no qodef-alignment--left \">\n    \t\t<h6 class=\"qodef-m-title\" >\n\t\t\t\t\tA PROPOS\t\t\t<\/h6>\n\t    <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-0535ffa elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0535ffa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e48ab65\" data-id=\"e48ab65\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-afa5333 elementor-widget elementor-widget-marity_core_section_title\" data-id=\"afa5333\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"marity_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-show_supertitle--no qodef-alignment--left \">\n    \t\t<h1 class=\"qodef-m-title\" style=\"color: #16193D\">\n\t\t\t\t\tQui sommes-nous ?\t\t\t<\/h1>\n\t\t<p class=\"qodef-m-text\" style=\"margin-top: 37px;color: #16193D\">Cr\u00e9\u00e9e en 2005, Dynamika a pour vocation d\u2019innover dans le domaine des activit\u00e9s aquatiques et du Spa. Fabricant fran\u00e7ais, de la conception \u00e0 la distribution, Dynamika a cr\u00e9\u00e9 un v\u00e9ritable p\u00f4le industriel en r\u00e9gion Aquitaine. Pionnier de l\u2019aquabiking en France dans les ann\u00e9es 2000, Dynamika est aujourd\u2019hui leader dans le domaine de la remise en forme par l\u2019eau et n\u2019a cess\u00e9 d\u2019innover pour rendre les activit\u00e9s et soins dans l\u2019eau plus efficaces.<\/p>\n    <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8bce15 elementor-widget elementor-widget-spacer\" data-id=\"a8bce15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-4d5d291 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4d5d291\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0b5fe38\" data-id=\"0b5fe38\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fd31aa elementor-widget elementor-widget-marity_core_single_image\" data-id=\"4fd31aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"marity_core_single_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-single-image qodef-layout--default   qodef--morph-mask \" style=\"--qodef--morph-shape-position-x: -11%\">\n\t                    <div class=\"qodef-svg-morph-holder qodef-type-1\">\n                <svg class=\"qodef-svg--clip-morph-shape-1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"1059.2\" height=\"1059.2\" viewBox=\"0 0 1059.2 1059.2\"><clipPath id=\"marity-1-340\" clipPathUnits=\"objectBoundingBox\"><path d= \"M293.4 1054.6c151.2 16.3 190.8-118 307.3-130.9 61.7-6.9 133.6 22 200.1 30.1 274.5 33.6 350.5-435.6 114.1-655.2-62.6-58.2-171.6-106.5-246.4-127.6C455 110.9 80.3-133 7.2 96.5c-22.7 71.8 13.3 254.5 43 336.6C118 619.2 33.7 852 144.5 976.9a241 241 0 0 0 148.9 77.7Z\"\/><path d= \"M282.5 1042.6c149 16.2 169-140.3 283.7-153.3 60.8-6.8 123.5 38 189 46.1 262 40 418.4-457.7 174.3-655-61.7-58.3-207-70-280.6-91.1-210.2-60.3-538.5-297-610.4-67.1-22.5 71.9 12 227.3 41.4 309.4 66.6 186.5-75.6 394.7 33.4 519.8 39.1 44.9 118.7 85.6 169.4 91.2Z\"\/><path d= \"M267.9 1054.3c148.7 17.4 135-158 249.7-171.7 60.6-7.4 182.1 26.5 247.6 35.2 261.5 42.7 415.6-511.7 171.8-722.2-61.7-62.2-250 4.4-323.6-18.1-209.9-64.3-405.4-224-543.2-60.8-47 80-4.4 216.3 25 304 66.5 198.8-53 307.2 24.9 497 27 81.1 97.2 130.7 147.8 136.6Z\"\/><\/clipPath><\/svg>            <\/div>\n        \t\t<div class=\"qodef-m-image\">\n\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2000\" height=\"1334\" src=\"https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/DYNAMIKA-AMBIANCES-PRODUITS-16-04-2025-009.jpg\" class=\"attachment-full size-full\" alt=\"Tapis longue bande Spa Jogger\" srcset=\"https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/DYNAMIKA-AMBIANCES-PRODUITS-16-04-2025-009.jpg 2000w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/DYNAMIKA-AMBIANCES-PRODUITS-16-04-2025-009-300x200.jpg 300w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/DYNAMIKA-AMBIANCES-PRODUITS-16-04-2025-009-1024x683.jpg 1024w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/DYNAMIKA-AMBIANCES-PRODUITS-16-04-2025-009-768x512.jpg 768w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/DYNAMIKA-AMBIANCES-PRODUITS-16-04-2025-009-1536x1025.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1033445\" data-id=\"1033445\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad59f7d elementor-widget elementor-widget-marity_core_section_title\" data-id=\"ad59f7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"marity_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-show_supertitle--no qodef-alignment--left \">\n    \t\t<h2 class=\"qodef-m-title\" style=\"color: #16193D\">\n\t\t\t\t\tDes produits r\u00e9sistants pour offrir le meilleur\t\t\t<\/h2>\n\t\t<p class=\"qodef-m-text\" style=\"margin-top: 40px;color: #16193D\">Les mat\u00e9riaux et composants d\u2019origine fran\u00e7aise et pays limitrophes garantissent une excellente tenue dans le temps (r\u00e9sine anti-osmose, inox marin, \u00e9lectronique fran\u00e7aise, pompes allemande, etc..).<\/p>\n    <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-5f89bdf elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5f89bdf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3b04b67\" data-id=\"3b04b67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0765eec elementor-widget elementor-widget-marity_core_section_title\" data-id=\"0765eec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"marity_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-show_supertitle--no qodef-alignment--left \">\n    \t\t<h1 class=\"qodef-m-title\" style=\"color: #16193D\">\n\t\t\t\t\tLa technologie au coeur de l'innovation\t\t\t<\/h1>\n\t\t<p class=\"qodef-m-text\" style=\"margin-top: 37px;color: #16193D\">Un processus d\u2019am\u00e9lioration continue, des partenariats industriels fran\u00e7ais et un budget d\u2019investissement de 15 \u00e0 20% du chiffre d\u2019affaires garantissent la p\u00e9rennit\u00e9 de votre investissement.<\/p>\n    <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a2804b3\" data-id=\"a2804b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4b0ace elementor-widget__width-auto elementor-widget elementor-widget-marity_core_single_image\" data-id=\"d4b0ace\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"marity_core_single_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-single-image qodef-layout--default   qodef--morph-mask \" style=\"--qodef--morph-shape-position-x: 2%;--qodef--morph-shape-scale-x: 1.4\">\n\t                    <div class=\"qodef-svg-morph-holder qodef-type-1\">\n                <svg class=\"qodef-svg--clip-morph-shape-1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"1059.2\" height=\"1059.2\" viewBox=\"0 0 1059.2 1059.2\"><clipPath id=\"marity-2-580\" clipPathUnits=\"objectBoundingBox\"><path d= \"M293.4 1054.6c151.2 16.3 190.8-118 307.3-130.9 61.7-6.9 133.6 22 200.1 30.1 274.5 33.6 350.5-435.6 114.1-655.2-62.6-58.2-171.6-106.5-246.4-127.6C455 110.9 80.3-133 7.2 96.5c-22.7 71.8 13.3 254.5 43 336.6C118 619.2 33.7 852 144.5 976.9a241 241 0 0 0 148.9 77.7Z\"\/><path d= \"M282.5 1042.6c149 16.2 169-140.3 283.7-153.3 60.8-6.8 123.5 38 189 46.1 262 40 418.4-457.7 174.3-655-61.7-58.3-207-70-280.6-91.1-210.2-60.3-538.5-297-610.4-67.1-22.5 71.9 12 227.3 41.4 309.4 66.6 186.5-75.6 394.7 33.4 519.8 39.1 44.9 118.7 85.6 169.4 91.2Z\"\/><path d= \"M267.9 1054.3c148.7 17.4 135-158 249.7-171.7 60.6-7.4 182.1 26.5 247.6 35.2 261.5 42.7 415.6-511.7 171.8-722.2-61.7-62.2-250 4.4-323.6-18.1-209.9-64.3-405.4-224-543.2-60.8-47 80-4.4 216.3 25 304 66.5 198.8-53 307.2 24.9 497 27 81.1 97.2 130.7 147.8 136.6Z\"\/><\/clipPath><\/svg>            <\/div>\n        \t\t<div class=\"qodef-m-image\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1714\" src=\"https:\/\/dynamika.com\/wp-content\/uploads\/2025\/06\/Ht2Jk1J0-scaled.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dynamika.com\/wp-content\/uploads\/2025\/06\/Ht2Jk1J0-scaled.jpeg 2560w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/06\/Ht2Jk1J0-300x201.jpeg 300w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/06\/Ht2Jk1J0-1024x685.jpeg 1024w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/06\/Ht2Jk1J0-768x514.jpeg 768w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/06\/Ht2Jk1J0-1536x1028.jpeg 1536w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/06\/Ht2Jk1J0-2048x1371.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-ddd5d94 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ddd5d94\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fc5bca6\" data-id=\"fc5bca6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8920895 elementor-widget elementor-widget-marity_core_single_image\" data-id=\"8920895\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"marity_core_single_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-single-image qodef-layout--default   qodef--morph-mask \" style=\"--qodef--morph-shape-position-x: -11%\">\n\t                    <div class=\"qodef-svg-morph-holder qodef-type-1\">\n                <svg class=\"qodef-svg--clip-morph-shape-1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"1059.2\" height=\"1059.2\" viewBox=\"0 0 1059.2 1059.2\"><clipPath id=\"marity-3-948\" clipPathUnits=\"objectBoundingBox\"><path d= \"M293.4 1054.6c151.2 16.3 190.8-118 307.3-130.9 61.7-6.9 133.6 22 200.1 30.1 274.5 33.6 350.5-435.6 114.1-655.2-62.6-58.2-171.6-106.5-246.4-127.6C455 110.9 80.3-133 7.2 96.5c-22.7 71.8 13.3 254.5 43 336.6C118 619.2 33.7 852 144.5 976.9a241 241 0 0 0 148.9 77.7Z\"\/><path d= \"M282.5 1042.6c149 16.2 169-140.3 283.7-153.3 60.8-6.8 123.5 38 189 46.1 262 40 418.4-457.7 174.3-655-61.7-58.3-207-70-280.6-91.1-210.2-60.3-538.5-297-610.4-67.1-22.5 71.9 12 227.3 41.4 309.4 66.6 186.5-75.6 394.7 33.4 519.8 39.1 44.9 118.7 85.6 169.4 91.2Z\"\/><path d= \"M267.9 1054.3c148.7 17.4 135-158 249.7-171.7 60.6-7.4 182.1 26.5 247.6 35.2 261.5 42.7 415.6-511.7 171.8-722.2-61.7-62.2-250 4.4-323.6-18.1-209.9-64.3-405.4-224-543.2-60.8-47 80-4.4 216.3 25 304 66.5 198.8-53 307.2 24.9 497 27 81.1 97.2 130.7 147.8 136.6Z\"\/><\/clipPath><\/svg>            <\/div>\n        \t\t<div class=\"qodef-m-image\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2000\" height=\"1334\" src=\"https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/DYNAMIKA-AMBIANCES-PRODUITS-16-04-2025-011.jpg\" class=\"attachment-full size-full\" alt=\"Ecran des programmes Spa Jogger\" srcset=\"https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/DYNAMIKA-AMBIANCES-PRODUITS-16-04-2025-011.jpg 2000w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/DYNAMIKA-AMBIANCES-PRODUITS-16-04-2025-011-300x200.jpg 300w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/DYNAMIKA-AMBIANCES-PRODUITS-16-04-2025-011-1024x683.jpg 1024w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/DYNAMIKA-AMBIANCES-PRODUITS-16-04-2025-011-768x512.jpg 768w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/DYNAMIKA-AMBIANCES-PRODUITS-16-04-2025-011-1536x1025.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8f3c75f\" data-id=\"8f3c75f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc0ed5f elementor-widget elementor-widget-marity_core_section_title\" data-id=\"fc0ed5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"marity_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-show_supertitle--no qodef-alignment--left \">\n    \t\t<h2 class=\"qodef-m-title\" style=\"color: #16193D\">\n\t\t\t\t\tProduits brevet\u00e9s\t\t\t<\/h2>\n\t\t<p class=\"qodef-m-text\" style=\"margin-top: 40px;color: #16193D\">Plusieurs brevets europ\u00e9ens ont \u00e9t\u00e9 d\u00e9pos\u00e9s pour prot\u00e9ger les innovations Dynamika. En particulier les brevets N\u00b0 0951712 et 1262011 garantissent une protection et diff\u00e9rentiation de vos investissements\n\n<\/p>\n    <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-fb44358 e-flex e-con-boxed e-con e-parent\" data-id=\"fb44358\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-430f1e1 elementor-widget elementor-widget-spacer\" data-id=\"430f1e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-12f657a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"12f657a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b7f1146\" data-id=\"b7f1146\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-442677c elementor-widget elementor-widget-marity_core_process_info_tabs\" data-id=\"442677c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"marity_core_process_info_tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-process-info-tabs qodef-layout--horizontal  qodef-appearance--morph   qodef--has-appear   qodef-enable-min-height--yes qodef-items--3 qodef-no-of-items--odd qodef-grid qodef-layout--columns qodef-col-num--3 qodef-gutter--tiny qodef-responsive--custom qodef-col-num--1440--3 qodef-col-num--1366--3 qodef-col-num--1024--3 qodef-col-num--768--1 qodef-col-num--680--1 qodef-col-num--480--1\">\n\t<div class=\"qodef-grid-inner qodef-process-info-tabs-holder\">\n\t\t\t\t            \t\t\t<div class=\"qodef-grid-item qodef-process-info-tabs-item-holder\">\n\t\t\t\t<div class=\"qodef-process-info-tabs-item qodef--has-appear\" style=\"background-color: #F4F4F4\">\n                                            <div id=\"qodef-svg-morph-2240\" class=\"qodef-svg-morph-holder qodef-type-1\" style=\"color: #EFEFEF\">\n                            <svg class=\"qodef-svg--morph-shape-1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"684.0455\" height=\"438.6857\" viewBox=\"0 0 684.0455 438.6857\"><path fill=\"currentColor\" d=\"M 676 170.7 C 656.8 126.9 593.6 102.2 550.3 119.4 C 461 154.7 470.3 105.7 458.7 66.7 C 453.7 -0.4 396.1 -8.5 357 8.6 C 335.2 18.1 325.2 53 320 74 L 319.9 73.9 Q 319.8 74.3 319.7 74.8 A 54.7 54.7 0 0 1 250.3 113.7 C 232.6 108.1 216 84.6 175.1 82.9 C 79.3 79.1 -0 168 -0 254.6 S 83.1 439.6 179 439.6 C 259.6 439.6 288.3 341.6 320 297.6 C 354 250.5 431.4 268.9 473.7 308.6 C 505.4 339.5 563 368.2 607.2 348.9 C 664.9 323.7 698.6 225.7 676 172.9 Z\" \/><path fill=\"currentColor\" d=\"M 690.9 102.3 C 671.7 58.5 606.9 20.1 569.1 47.4 C 488.1 106.1 444.3 97.4 432.7 58.4 C 427.7 -8.7 384.7 -4.8 345.6 12.3 C 323.8 21.8 325.2 53 320 74 C 320 74 319.9 73.9 319.9 73.9 C 319.8 74.2 319.8 74.5 319.7 74.8 C 316 89.4 327.6 123.3 275.6 146 C 261.8 152 217.2 119.8 210.8 106.3 C 178 37.5 148 44.3 107.1 42.6 C 11.3 38.8 -8 199 -8 285.6 C -8 372.2 83.1 439.6 179 439.6 C 259.6 439.6 277.3 354.6 291.8 302.4 C 306.8 248.2 414.6 224.8 436.4 278.6 C 465.2 350 531.8 368 575.8 348 C 638 319.7 717.3 274.4 692.9 104.1 C 692.9 103.4 690.9 103 690.9 102.3\" \/><\/svg>                        <\/div>\n                    \t\t\t\t\t<div class=\"qodef-process-info-tabs-content\">\n                        \t\t\t\t\t\t    <h4 itemprop=\"name\" class=\"qodef-e-title entry-title\">\n        Nos valeurs    <\/h4>\n                        \t<p class=\"qodef-e-text\">Les valeurs de l\u2019entreprise sont l\u2019expertise, l\u2019inventivit\u00e9, la performance, la g\u00e9n\u00e9rosit\u00e9 et le dynamisme. Ces valeurs se retrouvent dans nos \u00e9quipes form\u00e9s de techniciens, ing\u00e9nieurs et professionnels des m\u00e9tiers de la forme et de la sant\u00e9.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"qodef-process-info-tabs-content-bottom\">\n\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t            \t\t\t<div class=\"qodef-grid-item qodef-process-info-tabs-item-holder\">\n\t\t\t\t<div class=\"qodef-process-info-tabs-item qodef--has-appear\" style=\"background-color: #F0F8FD\">\n                                            <div id=\"qodef-svg-morph-7050\" class=\"qodef-svg-morph-holder qodef-type-2\" style=\"color: #E6F1F8\">\n                            <svg class=\"qodef-svg--morph-shape-2\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"510.1197\" height=\"445.5398\" viewBox=\"0 0 510.1197 445.5398\"><path fill=\"currentColor\" d=\"M323.62,87S227.4807,76.2858,173.63,26.2075-22.8027-2.925,3.12,107.6667,29.9139,222.1808,15.62,295,10.0644,416.3612,64.7572,439.7316,193.04,407.1581,244.2863,425.6667c73.7776,26.6458,145.3425,41.4413,226.0793-57.6634,35.3489-43.3911,47.2463-90.1121,25.1763-144.3886C466.2863,151.6667,424.953,105,323.62,87Z\" \/><path fill=\"currentColor\" d=\"M314.0439,104.78S227.4807,76.2858,173.63,26.2075-19.6211-4.7466,6.3013,105.845,46.8108,223.8882,32.5166,296.7074,10.0644,416.3612,64.7572,439.7316s126.2646-57.7086,177.511-39.2c73.7776,26.6458,147.3606,66.5764,228.0975-32.5284,35.3489-43.3911,54.9722-93.9383,25.1763-144.3886C455.336,155.5379,387.4925,123.518,314.0439,104.78Z\" \/><\/svg>;                        <\/div>\n                    \t\t\t\t\t<div class=\"qodef-process-info-tabs-content\">\n                        \t\t\t\t\t\t    <h4 itemprop=\"name\" class=\"qodef-e-title entry-title\">\n        Notre positionnement    <\/h4>\n                        \t<p class=\"qodef-e-text\">Dynamika, expert de la forme et sant\u00e9 par l\u2019eau. Gr\u00e2ce \u00e0 notre expertise industrielle, nous concevons des \u00e9quipements innovants, toujours en avance, pour r\u00e9pondre aux besoins des professionnels de la sant\u00e9 comme des particuliers.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"qodef-process-info-tabs-content-bottom\">\n\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t            \t\t\t<div class=\"qodef-grid-item qodef-process-info-tabs-item-holder\">\n\t\t\t\t<div class=\"qodef-process-info-tabs-item qodef--has-appear\" style=\"background-color: #F3F3F3\">\n                                            <div id=\"qodef-svg-morph-9935\" class=\"qodef-svg-morph-holder qodef-type-1\" style=\"color: #EFEFEF\">\n                            <svg class=\"qodef-svg--morph-shape-1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"684.0455\" height=\"438.6857\" viewBox=\"0 0 684.0455 438.6857\"><path fill=\"currentColor\" d=\"M 676 170.7 C 656.8 126.9 593.6 102.2 550.3 119.4 C 461 154.7 470.3 105.7 458.7 66.7 C 453.7 -0.4 396.1 -8.5 357 8.6 C 335.2 18.1 325.2 53 320 74 L 319.9 73.9 Q 319.8 74.3 319.7 74.8 A 54.7 54.7 0 0 1 250.3 113.7 C 232.6 108.1 216 84.6 175.1 82.9 C 79.3 79.1 -0 168 -0 254.6 S 83.1 439.6 179 439.6 C 259.6 439.6 288.3 341.6 320 297.6 C 354 250.5 431.4 268.9 473.7 308.6 C 505.4 339.5 563 368.2 607.2 348.9 C 664.9 323.7 698.6 225.7 676 172.9 Z\" \/><path fill=\"currentColor\" d=\"M 690.9 102.3 C 671.7 58.5 606.9 20.1 569.1 47.4 C 488.1 106.1 444.3 97.4 432.7 58.4 C 427.7 -8.7 384.7 -4.8 345.6 12.3 C 323.8 21.8 325.2 53 320 74 C 320 74 319.9 73.9 319.9 73.9 C 319.8 74.2 319.8 74.5 319.7 74.8 C 316 89.4 327.6 123.3 275.6 146 C 261.8 152 217.2 119.8 210.8 106.3 C 178 37.5 148 44.3 107.1 42.6 C 11.3 38.8 -8 199 -8 285.6 C -8 372.2 83.1 439.6 179 439.6 C 259.6 439.6 277.3 354.6 291.8 302.4 C 306.8 248.2 414.6 224.8 436.4 278.6 C 465.2 350 531.8 368 575.8 348 C 638 319.7 717.3 274.4 692.9 104.1 C 692.9 103.4 690.9 103 690.9 102.3\" \/><\/svg>                        <\/div>\n                    \t\t\t\t\t<div class=\"qodef-process-info-tabs-content\">\n                        \t\t\t\t\t\t    <h4 itemprop=\"name\" class=\"qodef-e-title entry-title\">\n        Nos points forts    <\/h4>\n                        \t<p class=\"qodef-e-text\">Un centre de recherche et fabrication en France , une exp\u00e9rience industrielle et m\u00e9tier dans les activit\u00e9s de remise en forme et sant\u00e9 par l\u2019eau en piscine et cabines.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"qodef-process-info-tabs-content-bottom\">\n\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-db1b7f1 e-flex e-con-boxed e-con e-parent\" data-id=\"db1b7f1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38f8250 elementor-widget elementor-widget-heading\" data-id=\"38f8250\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">They talk about us<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be5a2a0 elementor-widget elementor-widget-spacer\" data-id=\"be5a2a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-2f3fb24 e-flex e-con-boxed e-con e-parent\" data-id=\"2f3fb24\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-966d6d6 e-con-full e-flex e-con e-child\" data-id=\"966d6d6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15ccc5a elementor-widget elementor-widget-image\" data-id=\"15ccc5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"374\" src=\"https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/TF1_logo_2006.svg-1024x374.png\" class=\"attachment-large size-large wp-image-16884\" alt=\"logo tf1\" srcset=\"https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/TF1_logo_2006.svg-1024x374.png 1024w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/TF1_logo_2006.svg-300x110.png 300w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/TF1_logo_2006.svg-768x281.png 768w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/TF1_logo_2006.svg-1536x561.png 1536w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/TF1_logo_2006.svg-2048x748.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-63c6e02 e-con-full e-flex e-con e-child\" data-id=\"63c6e02\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b408813 elementor-widget elementor-widget-spacer\" data-id=\"b408813\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe12414 elementor-widget elementor-widget-image\" data-id=\"fe12414\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"826\" src=\"https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/Logo_Sud_Ouest.svg-1024x826.png\" class=\"attachment-large size-large wp-image-16883\" alt=\"logo sud ouest\" srcset=\"https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/Logo_Sud_Ouest.svg-1024x826.png 1024w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/Logo_Sud_Ouest.svg-300x242.png 300w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/Logo_Sud_Ouest.svg-768x620.png 768w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/Logo_Sud_Ouest.svg-1536x1240.png 1536w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/Logo_Sud_Ouest.svg-2048x1653.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b78930 elementor-widget elementor-widget-spacer\" data-id=\"4b78930\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-d943843 e-con-full e-flex e-con e-child\" data-id=\"d943843\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae1a1eb elementor-widget elementor-widget-image\" data-id=\"ae1a1eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/Logo_M6_2020_fond_clair.svg-1024x768.png\" class=\"attachment-large size-large wp-image-16882\" alt=\"logo M6\" srcset=\"https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/Logo_M6_2020_fond_clair.svg-1024x768.png 1024w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/Logo_M6_2020_fond_clair.svg-300x225.png 300w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/Logo_M6_2020_fond_clair.svg-768x576.png 768w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/Logo_M6_2020_fond_clair.svg-1536x1153.png 1536w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/Logo_M6_2020_fond_clair.svg-2048x1537.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-a90f4c9 e-con-full e-flex e-con e-child\" data-id=\"a90f4c9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d559f0 elementor-widget elementor-widget-spacer\" data-id=\"3d559f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37217cd elementor-widget elementor-widget-image\" data-id=\"37217cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"952\" src=\"https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/france_3_logo_rvb_3_couleur_noir-1024x952.png\" class=\"attachment-large size-large wp-image-16881\" alt=\"logo france 3\" srcset=\"https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/france_3_logo_rvb_3_couleur_noir-1024x952.png 1024w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/france_3_logo_rvb_3_couleur_noir-300x279.png 300w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/france_3_logo_rvb_3_couleur_noir-768x714.png 768w, https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/france_3_logo_rvb_3_couleur_noir.png 1178w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c062e2f elementor-widget elementor-widget-spacer\" data-id=\"c062e2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-754f24e e-flex e-con-boxed e-con e-parent\" data-id=\"754f24e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a80a69 elementor-widget elementor-widget-spacer\" data-id=\"2a80a69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>A PROPOS Qui sommes-nous ? Cr\u00e9\u00e9e en 2005, Dynamika a pour vocation d\u2019innover dans le domaine des activit\u00e9s aquatiques et du Spa. Fabricant fran\u00e7ais, de la conception \u00e0 la distribution, Dynamika a cr\u00e9\u00e9 un v\u00e9ritable p\u00f4le industriel en r\u00e9gion Aquitaine. Pionnier de l\u2019aquabiking en France dans les ann\u00e9es 2000, Dynamika est aujourd\u2019hui leader dans le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-full-width.php","meta":{"footnotes":""},"class_list":["post-19737","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>About Us - Dynamika - Dynamika<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dynamika.com\/a-propos-de-nous\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About Us - Dynamika - Dynamika\" \/>\n<meta property=\"og:description\" content=\"A PROPOS Qui sommes-nous ? Cr\u00e9\u00e9e en 2005, Dynamika a pour vocation d\u2019innover dans le domaine des activit\u00e9s aquatiques et du Spa. Fabricant fran\u00e7ais, de la conception \u00e0 la distribution, Dynamika a cr\u00e9\u00e9 un v\u00e9ritable p\u00f4le industriel en r\u00e9gion Aquitaine. Pionnier de l\u2019aquabiking en France dans les ann\u00e9es 2000, Dynamika est aujourd\u2019hui leader dans le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dynamika.com\/a-propos-de-nous\/\" \/>\n<meta property=\"og:site_name\" content=\"Dynamika\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-30T13:42:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/DYNAMIKA-AMBIANCES-PRODUITS-16-04-2025-009.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dynamika.com\/a-propos-de-nous\/\",\"url\":\"https:\/\/dynamika.com\/a-propos-de-nous\/\",\"name\":\"About Us - Dynamika - Dynamika\",\"isPartOf\":{\"@id\":\"https:\/\/dynamika.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dynamika.com\/a-propos-de-nous\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dynamika.com\/a-propos-de-nous\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/DYNAMIKA-AMBIANCES-PRODUITS-16-04-2025-009.jpg\",\"datePublished\":\"2022-11-09T13:44:02+00:00\",\"dateModified\":\"2025-06-30T13:42:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dynamika.com\/a-propos-de-nous\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dynamika.com\/a-propos-de-nous\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dynamika.com\/a-propos-de-nous\/#primaryimage\",\"url\":\"https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/DYNAMIKA-AMBIANCES-PRODUITS-16-04-2025-009.jpg\",\"contentUrl\":\"https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/DYNAMIKA-AMBIANCES-PRODUITS-16-04-2025-009.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dynamika.com\/a-propos-de-nous\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dynamika.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About Us &#8211; Dynamika\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dynamika.com\/#website\",\"url\":\"https:\/\/dynamika.com\/\",\"name\":\"Dynamika\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dynamika.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dynamika.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dynamika.com\/#organization\",\"name\":\"Dynamika\",\"url\":\"https:\/\/dynamika.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dynamika.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dynamika.com\/wp-content\/uploads\/2024\/03\/bien.png\",\"contentUrl\":\"https:\/\/dynamika.com\/wp-content\/uploads\/2024\/03\/bien.png\",\"width\":900,\"height\":420,\"caption\":\"Dynamika\"},\"image\":{\"@id\":\"https:\/\/dynamika.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"About Us - Dynamika - Dynamika","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dynamika.com\/a-propos-de-nous\/","og_locale":"en_US","og_type":"article","og_title":"About Us - Dynamika - Dynamika","og_description":"A PROPOS Qui sommes-nous ? Cr\u00e9\u00e9e en 2005, Dynamika a pour vocation d\u2019innover dans le domaine des activit\u00e9s aquatiques et du Spa. Fabricant fran\u00e7ais, de la conception \u00e0 la distribution, Dynamika a cr\u00e9\u00e9 un v\u00e9ritable p\u00f4le industriel en r\u00e9gion Aquitaine. Pionnier de l\u2019aquabiking en France dans les ann\u00e9es 2000, Dynamika est aujourd\u2019hui leader dans le [&hellip;]","og_url":"https:\/\/dynamika.com\/a-propos-de-nous\/","og_site_name":"Dynamika","article_modified_time":"2025-06-30T13:42:31+00:00","og_image":[{"url":"https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/DYNAMIKA-AMBIANCES-PRODUITS-16-04-2025-009.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dynamika.com\/a-propos-de-nous\/","url":"https:\/\/dynamika.com\/a-propos-de-nous\/","name":"About Us - Dynamika - Dynamika","isPartOf":{"@id":"https:\/\/dynamika.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dynamika.com\/a-propos-de-nous\/#primaryimage"},"image":{"@id":"https:\/\/dynamika.com\/a-propos-de-nous\/#primaryimage"},"thumbnailUrl":"https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/DYNAMIKA-AMBIANCES-PRODUITS-16-04-2025-009.jpg","datePublished":"2022-11-09T13:44:02+00:00","dateModified":"2025-06-30T13:42:31+00:00","breadcrumb":{"@id":"https:\/\/dynamika.com\/a-propos-de-nous\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dynamika.com\/a-propos-de-nous\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dynamika.com\/a-propos-de-nous\/#primaryimage","url":"https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/DYNAMIKA-AMBIANCES-PRODUITS-16-04-2025-009.jpg","contentUrl":"https:\/\/dynamika.com\/wp-content\/uploads\/2025\/05\/DYNAMIKA-AMBIANCES-PRODUITS-16-04-2025-009.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/dynamika.com\/a-propos-de-nous\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dynamika.com\/"},{"@type":"ListItem","position":2,"name":"About Us &#8211; Dynamika"}]},{"@type":"WebSite","@id":"https:\/\/dynamika.com\/#website","url":"https:\/\/dynamika.com\/","name":"Dynamika","description":"","publisher":{"@id":"https:\/\/dynamika.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dynamika.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dynamika.com\/#organization","name":"Dynamika","url":"https:\/\/dynamika.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dynamika.com\/#\/schema\/logo\/image\/","url":"https:\/\/dynamika.com\/wp-content\/uploads\/2024\/03\/bien.png","contentUrl":"https:\/\/dynamika.com\/wp-content\/uploads\/2024\/03\/bien.png","width":900,"height":420,"caption":"Dynamika"},"image":{"@id":"https:\/\/dynamika.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dynamika.com\/en\/wp-json\/wp\/v2\/pages\/19737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dynamika.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dynamika.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dynamika.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dynamika.com\/en\/wp-json\/wp\/v2\/comments?post=19737"}],"version-history":[{"count":16,"href":"https:\/\/dynamika.com\/en\/wp-json\/wp\/v2\/pages\/19737\/revisions"}],"predecessor-version":[{"id":21067,"href":"https:\/\/dynamika.com\/en\/wp-json\/wp\/v2\/pages\/19737\/revisions\/21067"}],"wp:attachment":[{"href":"https:\/\/dynamika.com\/en\/wp-json\/wp\/v2\/media?parent=19737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}